{"id":3965,"date":"2020-02-24T19:44:18","date_gmt":"2020-02-24T18:44:18","guid":{"rendered":"http:\/\/dev.hotel-marcopolo.com\/?page_id=3965"},"modified":"2024-05-29T15:27:56","modified_gmt":"2024-05-29T13:27:56","slug":"meet-the-team","status":"publish","type":"page","link":"https:\/\/hotel-marcopolo.com\/en\/meet-the-team\/","title":{"rendered":"Meet The Team"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row full_width=&#8221;stretch_row_content&#8221; css=&#8221;.vc_custom_1582570039398{background-color: #0f2453 !important;}&#8221;][vc_column width=&#8221;1\/3&#8243;]<h5 class=\"calluna-heading calluna-heading-single-line text-align-center \" style=\"color: #967a50;\"><span>Director: Stipe Mili\u0161i\u0107<\/span><\/h5>[\/vc_column][vc_column width=&#8221;1\/3&#8243;]<h5 class=\"calluna-heading calluna-heading-single-line text-align-center \" style=\"color: #967a50;\"><span>FB Manager:<\/span><\/h5>[\/vc_column][vc_column width=&#8221;1\/3&#8243;]<h5 class=\"calluna-heading calluna-heading-single-line text-align-center \" style=\"color: #967a50;\"><span>FrontDesk Manager:<\/span><\/h5>[\/vc_column][vc_column][vc_single_image image=&#8221;3969&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row_content&#8221; css=&#8221;.vc_custom_1582570039398{background-color: #0f2453 !important;}&#8221;][vc_column width=&#8221;1\/3&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][vc_column][vc_single_image image=&#8221;3969&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3965","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meet The Team &#8211; Hotel Marco Polo<\/title>\n<meta name=\"description\" content=\"Hotel Marco Polo - meet our team\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel-marcopolo.com\/en\/meet-the-team\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meet The Team &#8211; Hotel Marco Polo\" \/>\n<meta property=\"og:description\" content=\"Hotel Marco Polo - meet our team\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel-marcopolo.com\/en\/meet-the-team\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Marco Polo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Boutiquehotelmarcopolo\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-29T13:27:56+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel-marcopolo.com\\\/en\\\/meet-the-team\\\/\",\"url\":\"https:\\\/\\\/hotel-marcopolo.com\\\/en\\\/meet-the-team\\\/\",\"name\":\"Meet The Team &#8211; Hotel Marco Polo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel-marcopolo.com\\\/hr\\\/#website\"},\"datePublished\":\"2020-02-24T18:44:18+00:00\",\"dateModified\":\"2024-05-29T13:27:56+00:00\",\"description\":\"Hotel Marco Polo - meet our team\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel-marcopolo.com\\\/en\\\/meet-the-team\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel-marcopolo.com\\\/en\\\/meet-the-team\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel-marcopolo.com\\\/en\\\/meet-the-team\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hotel-marcopolo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meet The Team\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel-marcopolo.com\\\/hr\\\/#website\",\"url\":\"https:\\\/\\\/hotel-marcopolo.com\\\/hr\\\/\",\"name\":\"Hotel Marco Polo\",\"description\":\"Boutique Hotel Marco Polo\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel-marcopolo.com\\\/hr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel-marcopolo.com\\\/hr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel-marcopolo.com\\\/hr\\\/#organization\",\"name\":\"Hotel Marco Polo\",\"url\":\"https:\\\/\\\/hotel-marcopolo.com\\\/hr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hotel-marcopolo.com\\\/hr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel-marcopolo.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/cropped-logo_512.png\",\"contentUrl\":\"https:\\\/\\\/hotel-marcopolo.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/cropped-logo_512.png\",\"width\":512,\"height\":512,\"caption\":\"Hotel Marco Polo\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel-marcopolo.com\\\/hr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Boutiquehotelmarcopolo\",\"https:\\\/\\\/www.instagram.com\\\/boutiquehotelmarcopolo\\\/\",\"https:\\\/\\\/youtube.com\\\/user\\\/HotelMarcoPoloCRO\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meet The Team &#8211; Hotel Marco Polo","description":"Hotel Marco Polo - meet our team","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel-marcopolo.com\/en\/meet-the-team\/","og_locale":"en_US","og_type":"article","og_title":"Meet The Team &#8211; Hotel Marco Polo","og_description":"Hotel Marco Polo - meet our team","og_url":"https:\/\/hotel-marcopolo.com\/en\/meet-the-team\/","og_site_name":"Hotel Marco Polo","article_publisher":"https:\/\/www.facebook.com\/Boutiquehotelmarcopolo","article_modified_time":"2024-05-29T13:27:56+00:00","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel-marcopolo.com\/en\/meet-the-team\/","url":"https:\/\/hotel-marcopolo.com\/en\/meet-the-team\/","name":"Meet The Team &#8211; Hotel Marco Polo","isPartOf":{"@id":"https:\/\/hotel-marcopolo.com\/hr\/#website"},"datePublished":"2020-02-24T18:44:18+00:00","dateModified":"2024-05-29T13:27:56+00:00","description":"Hotel Marco Polo - meet our team","breadcrumb":{"@id":"https:\/\/hotel-marcopolo.com\/en\/meet-the-team\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel-marcopolo.com\/en\/meet-the-team\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel-marcopolo.com\/en\/meet-the-team\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hotel-marcopolo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Meet The Team"}]},{"@type":"WebSite","@id":"https:\/\/hotel-marcopolo.com\/hr\/#website","url":"https:\/\/hotel-marcopolo.com\/hr\/","name":"Hotel Marco Polo","description":"Boutique Hotel Marco Polo","publisher":{"@id":"https:\/\/hotel-marcopolo.com\/hr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel-marcopolo.com\/hr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hotel-marcopolo.com\/hr\/#organization","name":"Hotel Marco Polo","url":"https:\/\/hotel-marcopolo.com\/hr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hotel-marcopolo.com\/hr\/#\/schema\/logo\/image\/","url":"https:\/\/hotel-marcopolo.com\/wp-content\/uploads\/2020\/02\/cropped-logo_512.png","contentUrl":"https:\/\/hotel-marcopolo.com\/wp-content\/uploads\/2020\/02\/cropped-logo_512.png","width":512,"height":512,"caption":"Hotel Marco Polo"},"image":{"@id":"https:\/\/hotel-marcopolo.com\/hr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Boutiquehotelmarcopolo","https:\/\/www.instagram.com\/boutiquehotelmarcopolo\/","https:\/\/youtube.com\/user\/HotelMarcoPoloCRO"]}]}},"_links":{"self":[{"href":"https:\/\/hotel-marcopolo.com\/en\/wp-json\/wp\/v2\/pages\/3965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel-marcopolo.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hotel-marcopolo.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hotel-marcopolo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel-marcopolo.com\/en\/wp-json\/wp\/v2\/comments?post=3965"}],"version-history":[{"count":6,"href":"https:\/\/hotel-marcopolo.com\/en\/wp-json\/wp\/v2\/pages\/3965\/revisions"}],"predecessor-version":[{"id":5215,"href":"https:\/\/hotel-marcopolo.com\/en\/wp-json\/wp\/v2\/pages\/3965\/revisions\/5215"}],"wp:attachment":[{"href":"https:\/\/hotel-marcopolo.com\/en\/wp-json\/wp\/v2\/media?parent=3965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}